{"id":4632,"date":"2025-10-21T10:49:18","date_gmt":"2025-10-21T10:49:18","guid":{"rendered":"https:\/\/mxmexhibitions.com\/iplastpackTanzania\/?page_id=4632"},"modified":"2025-10-21T11:07:36","modified_gmt":"2025-10-21T11:07:36","slug":"exhibiting-application","status":"publish","type":"page","link":"https:\/\/mxmexhibitions.com\/iplastpackTanzania\/exhibiting-application\/","title":{"rendered":"Exhibiting Application"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"4632\" class=\"elementor elementor-4632\">\n\t\t\t\t<div class=\"elementor-element elementor-element-9a490a3 e-con-full e-flex e-con e-parent\" data-id=\"9a490a3\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-4ee08a6 e-con-full e-flex e-con e-child\" data-id=\"4ee08a6\" data-element_type=\"container\">\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-f9dc7e5 e-con-full e-flex e-con e-child\" data-id=\"f9dc7e5\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b145588 elementor-widget elementor-widget-heading\" data-id=\"b145588\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Request For Exhibiting Application<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-cf4ec6b elementor-widget elementor-widget-text-editor\" data-id=\"cf4ec6b\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p><style id=\"wpforms-css-vars-4627\">\n\t\t\t\t#wpforms-4627 {\n\t\t\t\t--wpforms-container-padding: 0px;\n--wpforms-container-border-width: 1px;\n--wpforms-container-border-radius: 3px;\n--wpforms-background-color: rgba(0, 0, 0, 0);\n--wpforms-field-size-input-height: 43px;\n--wpforms-field-size-input-spacing: 15px;\n--wpforms-field-size-font-size: 16px;\n--wpforms-field-size-line-height: 19px;\n--wpforms-field-size-padding-h: 14px;\n--wpforms-field-size-checkbox-size: 16px;\n--wpforms-field-size-sublabel-spacing: 5px;\n--wpforms-field-size-icon-size: 1;\n--wpforms-label-size-font-size: 16px;\n--wpforms-label-size-line-height: 19px;\n--wpforms-label-size-sublabel-font-size: 14px;\n--wpforms-label-size-sublabel-line-height: 17px;\n--wpforms-button-size-font-size: 17px;\n--wpforms-button-size-height: 41px;\n--wpforms-button-size-padding-h: 15px;\n--wpforms-button-size-margin-top: 10px;\n--wpforms-container-shadow-size-box-shadow: none;\n\t\t\t}\n\t\t\t<\/style><div class=\"wpforms-container wpforms-container-full wpforms-render-modern\" id=\"wpforms-4627\"><form id=\"wpforms-form-4627\" class=\"wpforms-validate wpforms-form wpforms-ajax-form\" data-formid=\"4627\" method=\"post\" enctype=\"multipart\/form-data\" action=\"\/iplastpackTanzania\/wp-json\/wp\/v2\/pages\/4632\" data-token=\"3fcacf23933777e591eb3a6ecfa4f7e3\" data-token-time=\"1784155033\"><noscript class=\"wpforms-error-noscript\">Please enable JavaScript in your browser to complete this form.<\/noscript><div id=\"wpforms-error-noscript\" style=\"display: none;\">Please enable JavaScript in your browser to complete this form.<\/div><div class=\"wpforms-field-container\">\t\t<div id=\"wpforms-4627-field_5-container\"\n\t\t\tclass=\"wpforms-field wpforms-field-text\"\n\t\t\tdata-field-type=\"text\"\n\t\t\tdata-field-id=\"5\"\n\t\t\t>\n\t\t\t<label class=\"wpforms-field-label\" for=\"wpforms-4627-field_5\" >Name Name Comment<\/label>\n\t\t\t<input type=\"text\" id=\"wpforms-4627-field_5\" class=\"wpforms-field-medium\" name=\"wpforms[fields][5]\" >\n\t\t<\/div>\n\t\t<div id=\"wpforms-4627-field_1-container\" class=\"wpforms-field wpforms-field-name\" data-field-id=\"1\"><fieldset><legend class=\"wpforms-field-label wpforms-label-hide\" aria-hidden=\"false\">Name <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/legend><div class=\"wpforms-field-row wpforms-field-large\"><div class=\"wpforms-field-row-block wpforms-first wpforms-one-half\"><input type=\"text\" id=\"wpforms-4627-field_1\" class=\"wpforms-field-name-first wpforms-field-required\" name=\"wpforms[fields][1][first]\" placeholder=\"First Name*\" aria-errormessage=\"wpforms-4627-field_1-error\" required><label for=\"wpforms-4627-field_1\" class=\"wpforms-field-sublabel after wpforms-sublabel-hide\">First<\/label><\/div><div class=\"wpforms-field-row-block wpforms-one-half\"><input type=\"text\" id=\"wpforms-4627-field_1-last\" class=\"wpforms-field-name-last wpforms-field-required\" name=\"wpforms[fields][1][last]\" placeholder=\"Last Name*\" aria-errormessage=\"wpforms-4627-field_1-last-error\" required><label for=\"wpforms-4627-field_1-last\" class=\"wpforms-field-sublabel after wpforms-sublabel-hide\">Last<\/label><\/div><\/div><\/fieldset><\/div><div id=\"wpforms-4627-field_2-container\" class=\"wpforms-field wpforms-field-email wpforms-one-half wpforms-first\" data-field-id=\"2\"><label class=\"wpforms-field-label wpforms-label-hide\" for=\"wpforms-4627-field_2\" aria-hidden=\"false\">Email <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><input type=\"email\" id=\"wpforms-4627-field_2\" class=\"wpforms-field-large wpforms-field-required\" name=\"wpforms[fields][2]\" placeholder=\"Your Email*\" spellcheck=\"false\" aria-errormessage=\"wpforms-4627-field_2-error\" required><\/div><div id=\"wpforms-4627-field_4-container\" class=\"wpforms-field wpforms-field-text wpforms-one-half\" data-field-id=\"4\"><label class=\"wpforms-field-label wpforms-label-hide\" for=\"wpforms-4627-field_4\" aria-hidden=\"false\">Company Name<\/label><input type=\"text\" id=\"wpforms-4627-field_4\" class=\"wpforms-field-large\" name=\"wpforms[fields][4]\" placeholder=\"Company Name\" aria-errormessage=\"wpforms-4627-field_4-error\" ><\/div><div id=\"wpforms-4627-field_3-container\" class=\"wpforms-field wpforms-field-textarea\" data-field-id=\"3\"><label class=\"wpforms-field-label wpforms-label-hide\" for=\"wpforms-4627-field_3\" aria-hidden=\"false\">Comment or Message<\/label><textarea id=\"wpforms-4627-field_3\" class=\"wpforms-field-large\" name=\"wpforms[fields][3]\" placeholder=\"Comment or Message\" aria-errormessage=\"wpforms-4627-field_3-error\" ><\/textarea><\/div><script>\n\t\t\t\t( function() {\n\t\t\t\t\tconst style = document.createElement( 'style' );\n\t\t\t\t\tstyle.appendChild( document.createTextNode( '#wpforms-4627-field_5-container { position: absolute !important; overflow: hidden !important; display: inline !important; height: 1px !important; width: 1px !important; z-index: -1000 !important; padding: 0 !important; } #wpforms-4627-field_5-container input { visibility: hidden; } #wpforms-conversational-form-page #wpforms-4627-field_5-container label { counter-increment: none; }' ) );\n\t\t\t\t\tdocument.head.appendChild( style );\n\t\t\t\t\tdocument.currentScript?.remove();\n\t\t\t\t} )();\n\t\t\t<\/script><\/div><!-- .wpforms-field-container --><div class=\"wpforms-submit-container\" ><input type=\"hidden\" name=\"wpforms[id]\" value=\"4627\"><input type=\"hidden\" name=\"page_title\" value=\"\"><input type=\"hidden\" name=\"page_url\" value=\"https:\/\/mxmexhibitions.com\/iplastpackTanzania\/wp-json\/wp\/v2\/pages\/4632\"><input type=\"hidden\" name=\"url_referer\" value=\"\"><button type=\"submit\" name=\"wpforms[submit]\" id=\"wpforms-submit-4627\" class=\"wpforms-submit\" data-alt-text=\"Sending...\" data-submit-text=\"Submit Application\" aria-live=\"assertive\" value=\"wpforms-submit\">Submit Application<\/button><img decoding=\"async\" src=\"https:\/\/mxmexhibitions.com\/iplastpackTanzania\/wp-content\/plugins\/wpforms-lite\/assets\/images\/submit-spin.svg\" class=\"wpforms-submit-spinner\" style=\"display: none;\" width=\"26\" height=\"26\" alt=\"Loading\"><\/div><\/form><\/div>  <!-- .wpforms-container --><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-65d1b5a e-con-full e-flex e-con e-child\" data-id=\"65d1b5a\" data-element_type=\"container\">\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Request For Exhibiting Application<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"footnotes":""},"class_list":["post-4632","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/mxmexhibitions.com\/iplastpackTanzania\/wp-json\/wp\/v2\/pages\/4632","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mxmexhibitions.com\/iplastpackTanzania\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/mxmexhibitions.com\/iplastpackTanzania\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/mxmexhibitions.com\/iplastpackTanzania\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/mxmexhibitions.com\/iplastpackTanzania\/wp-json\/wp\/v2\/comments?post=4632"}],"version-history":[{"count":29,"href":"https:\/\/mxmexhibitions.com\/iplastpackTanzania\/wp-json\/wp\/v2\/pages\/4632\/revisions"}],"predecessor-version":[{"id":4678,"href":"https:\/\/mxmexhibitions.com\/iplastpackTanzania\/wp-json\/wp\/v2\/pages\/4632\/revisions\/4678"}],"wp:attachment":[{"href":"https:\/\/mxmexhibitions.com\/iplastpackTanzania\/wp-json\/wp\/v2\/media?parent=4632"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}