{"id":5360,"date":"2025-11-06T10:59:58","date_gmt":"2025-11-06T10:59:58","guid":{"rendered":"https:\/\/mxmexhibitions.com\/iplastpackTanzania\/?page_id=5360"},"modified":"2025-11-06T11:21:03","modified_gmt":"2025-11-06T11:21:03","slug":"economy-package","status":"publish","type":"page","link":"https:\/\/mxmexhibitions.com\/iplastpackTanzania\/economy-package\/","title":{"rendered":"Economy Package"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"5360\" class=\"elementor elementor-5360\">\n\t\t\t\t        <section class=\"elementor-section elementor-inner-section elementor-element elementor-element-4ad469d4 elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4ad469d4\" data-element_type=\"section\">\n            \n                        <div class=\"elementor-container elementor-column-gap-extended \">\n                    <div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-61b4633f\" data-id=\"61b4633f\" data-element_type=\"column\">\n        <div class=\"elementor-widget-wrap elementor-element-populated\">\n                    \n        \t\t<div class=\"elementor-element elementor-element-f3fcd90 elementor-widget elementor-widget-ct_heading\" data-id=\"f3fcd90\" data-element_type=\"widget\" data-widget_type=\"ct_heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"ct-heading ct-heading-dot h-align- \" data-wow-duration=\"1.2s\">\r\n\t<div class=\"ct-heading--inner\">\r\n            \t\t<div class=\"item--sub-title style-default\">\r\n                <span>\r\n                       \r\n                    Economy Package                            \r\n                <\/span>\r\n            <\/div>\r\n    \t                <h4 class=\"item--title\">\r\n                            <i class=\"dot-shape\">\r\n                    <i><\/i>\r\n                    <i><\/i>\r\n                    <i><\/i>\r\n                    <i><\/i>\r\n                    <i><\/i>\r\n                    <i><\/i>\r\n                <\/i>\r\n                        Basic Provisions        <\/h4>\r\n    <\/div>\r\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e7f61ff elementor-widget elementor-widget-image\" data-id=\"e7f61ff\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"300\" height=\"169\" src=\"https:\/\/mxmexhibitions.com\/iplastpackTanzania\/wp-content\/uploads\/2025\/11\/economy-300x169.png\" class=\"attachment-medium size-medium wp-image-5362\" alt=\"\" srcset=\"https:\/\/mxmexhibitions.com\/iplastpackTanzania\/wp-content\/uploads\/2025\/11\/economy-300x169.png 300w, https:\/\/mxmexhibitions.com\/iplastpackTanzania\/wp-content\/uploads\/2025\/11\/economy-768x432.png 768w, https:\/\/mxmexhibitions.com\/iplastpackTanzania\/wp-content\/uploads\/2025\/11\/economy.png 800w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t            <\/div>\n        <\/div>\n                <div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-40d8ea2f\" data-id=\"40d8ea2f\" data-element_type=\"column\">\n        <div class=\"elementor-widget-wrap elementor-element-populated\">\n                    \n        \t\t<div class=\"elementor-element elementor-element-4f909f1c elementor-widget elementor-widget-ct_text_editor\" data-id=\"4f909f1c\" data-element_type=\"widget\" data-widget_type=\"ct_text_editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div id=\"ct_text_editor-4f909f1c\" class=\"ct-text-editor \">\n\t<div class=\"ct-item--inner\">\n\t\t<div class=\"ct-inline-css\"  data-css=\"\n\t        \">\n\t    <\/div>\n\t\t<div class=\"ct-text-editor elementor-clearfix\"><ul><li>9 Sqm Octanorm Stand<\/li><li>1 Table &#8211; 2 Chairs &#8211; Electrical Socket 220 Volts &#8211; 2 Spot Lights.<\/li><li>Company Name Fascia &amp; Carpet.<\/li><li>Listing in Exhibition Catalog.<\/li><li>4 nights \/ 5 days 4 **** Hotel Accommodation.<\/li><li>Airport to Hotel &amp; Back to Airport.<\/li><li>Hotel to Exhibition Centre &amp; Back to Hotel Transportation during exhibition days.<\/li><li>Break Fast.<\/li><li>All Taxes &amp; Registration.<\/li><\/ul><\/div>\n\t<\/div>\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t            <\/div>\n        <\/div>\n                    <\/div>\n        <\/section>\n                <section class=\"elementor-section elementor-inner-section elementor-element elementor-element-6193c23f elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6193c23f\" data-element_type=\"section\">\n            \n                        <div class=\"elementor-container elementor-column-gap-extended \">\n                    <div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-3b6cda6c\" data-id=\"3b6cda6c\" data-element_type=\"column\">\n        <div class=\"elementor-widget-wrap elementor-element-populated\">\n                    \n        \t\t<div class=\"elementor-element elementor-element-2030331b termmms elementor-widget elementor-widget-ct_heading\" data-id=\"2030331b\" data-element_type=\"widget\" data-widget_type=\"ct_heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"ct-heading ct-heading-dot h-align-center \" data-wow-duration=\"1.2s\">\r\n\t<div class=\"ct-heading--inner\">\r\n                        <h5 class=\"item--title\">\r\n                            <i class=\"dot-shape\">\r\n                    <i><\/i>\r\n                    <i><\/i>\r\n                    <i><\/i>\r\n                    <i><\/i>\r\n                    <i><\/i>\r\n                    <i><\/i>\r\n                <\/i>\r\n                        Payment Terms & Conditions\n        <\/h5>\r\n    <\/div>\r\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-75640735 elementor-widget elementor-widget-ct_text_editor\" data-id=\"75640735\" data-element_type=\"widget\" data-widget_type=\"ct_text_editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div id=\"ct_text_editor-75640735\" class=\"ct-text-editor \">\n\t<div class=\"ct-item--inner\">\n\t\t<div class=\"ct-inline-css\"  data-css=\"\n\t        \">\n\t    <\/div>\n\t\t<div class=\"ct-text-editor elementor-clearfix\"><p style=\"text-align: center\">Int\u2019l companies to pay by telex transfer in favour of \u201cmxm exhibition organizers \u201d.<\/p><p style=\"text-align: center\">Bank account no. <strong>2000829437<\/strong> , national bank of fujairah, dubai, uae. Swift code : <strong>nbfuaeafdxb<\/strong>.<\/p><p style=\"text-align: center\">Full \/ half payment to be made within 7 days of receiving our confirmation and invoice.Balance to be paid at least 45 days prior to the opening date of the exhibition.<\/p><p style=\"text-align: center\">Fees also includes registration and all taxes.<\/p><p style=\"text-align: center\">This is a legal document. Withdrawal will attract a minimum of 50% cancellation fees, if the organizer cancels the event, a full refund will apply.<\/p><p style=\"text-align: center\">The organizer reserves the right to cancel or relocate exhibitor to another location (of same size), if payment is not received by due date.<\/p><\/div>\n\t<\/div>\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t            <\/div>\n        <\/div>\n                    <\/div>\n        <\/section>\n                <section class=\"elementor-section elementor-top-section elementor-element elementor-element-48e2ae80 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"48e2ae80\" data-element_type=\"section\">\n            \n                        <div class=\"elementor-container elementor-column-gap-extended \">\n                    <div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-3b53e113\" data-id=\"3b53e113\" data-element_type=\"column\">\n        <div class=\"elementor-widget-wrap elementor-element-populated\">\n                    \n        \t\t<div class=\"elementor-element elementor-element-372553fa elementor-widget elementor-widget-ct_pricing\" data-id=\"372553fa\" data-element_type=\"widget\" data-widget_type=\"ct_pricing.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"ct-pricing ct-pricing-layout1 ct-pricing-tab-active\">\r\n            <div class=\"ct-pricing-tab-title\">\r\n                            <div class=\"ct-pricing-tab-item title-tab-monthly active\">Please Select The Desired Option<\/div>\r\n                                <\/div>\r\n        <div class=\"ct-pricing-tab-content\">\r\n                    <div class=\"ct-pricing-body ct-pricing-monthly pricing-3-column\">\r\n                                <div class=\"ct-pricing-item wow fadeInUp\" data-wow-duration=\"1.2s\">\r\n                    <div class=\"ct-pricing-item-inner \">\r\n                        <div class=\"item-popular\"><\/div>\r\n                        <h3 class=\"ct-pricing-title\">Option 1\t<\/h3>\r\n                        <div class=\"ct-pricing-subtitle\"><\/div>\r\n                        <div class=\"ct-pricing-price1\">$3265<\/div>\r\n                        \r\n                                                                            <div class=\"ct-pricing-icon\">\r\n                                                            <\/div>\r\n                        \r\n                        <div class=\"ct-pricing-desc\">One person plus single room accommodation inclusive of all above<\/div>\r\n                        <div class=\"ct-pricing-price2\"><\/div>\r\n\r\n                                                    <div class=\"ct-pricing-button\">\r\n                                <a class=\"btn btn-default\" href=\"#buy-now\">Buy Now<\/a>\r\n                            <\/div>\r\n                                            <\/div>\r\n                <\/div>\r\n                                <div class=\"ct-pricing-item wow fadeInUp\" data-wow-duration=\"1.2s\">\r\n                    <div class=\"ct-pricing-item-inner \">\r\n                        <div class=\"item-popular\"><\/div>\r\n                        <h3 class=\"ct-pricing-title\">Option 2<\/h3>\r\n                        <div class=\"ct-pricing-subtitle\"><\/div>\r\n                        <div class=\"ct-pricing-price1\">$3450<\/div>\r\n                        \r\n                                                                            <div class=\"ct-pricing-icon\">\r\n                                                            <\/div>\r\n                        \r\n                        <div class=\"ct-pricing-desc\">Two persons plus double room accommodation inclusive of all above<\/div>\r\n                        <div class=\"ct-pricing-price2\"><\/div>\r\n\r\n                                                    <div class=\"ct-pricing-button\">\r\n                                <a class=\"btn btn-default\" href=\"#buy-now\">Buy Now<\/a>\r\n                            <\/div>\r\n                                            <\/div>\r\n                <\/div>\r\n                                <div class=\"ct-pricing-item wow fadeInUp\" data-wow-duration=\"1.2s\">\r\n                    <div class=\"ct-pricing-item-inner \">\r\n                        <div class=\"item-popular\"><\/div>\r\n                        <h3 class=\"ct-pricing-title\">Option 3<\/h3>\r\n                        <div class=\"ct-pricing-subtitle\"><\/div>\r\n                        <div class=\"ct-pricing-price1\">$4200 <\/div>\r\n                        \r\n                                                                            <div class=\"ct-pricing-icon\">\r\n                                                            <\/div>\r\n                        \r\n                        <div class=\"ct-pricing-desc\">Two persons plus two separate rooms inclusive of all above<\/div>\r\n                        <div class=\"ct-pricing-price2\"><\/div>\r\n\r\n                                                    <div class=\"ct-pricing-button\">\r\n                                <a class=\"btn btn-default\" href=\"#buy-now\">Buy Now<\/a>\r\n                            <\/div>\r\n                                            <\/div>\r\n                <\/div>\r\n                            <\/div>\r\n                            <div class=\"ct-pricing-body ct-pricing-year ct-pricing-hide pricing-1-column\">\r\n                                <div class=\"ct-pricing-item\">\r\n                    <div class=\"ct-pricing-item-inner \">\r\n                        <div class=\"item-popular\"><\/div>\r\n                        <h3 class=\"ct-pricing-title\">Large Business<\/h3>\r\n                        <div class=\"ct-pricing-subtitle\">Unlimited Employees<\/div>\r\n                        <div class=\"ct-pricing-price1\">$699<\/div>\r\n                        \r\n                                                                            <div class=\"ct-pricing-icon\">\r\n                                                            <\/div>\r\n                        \r\n                        <div class=\"ct-pricing-desc\">Plus One-Time Bambee In-Depth HR Audit For:<\/div>\r\n                        <div class=\"ct-pricing-price2\">$3500<\/div>\r\n\r\n                                                    <div class=\"ct-pricing-button\">\r\n                                <a class=\"btn btn-default\" href=\"#buy-now #\">Try now<\/a>\r\n                            <\/div>\r\n                                            <\/div>\r\n                <\/div>\r\n                                <div class=\"ct-pricing-item\">\r\n                    <div class=\"ct-pricing-item-inner \">\r\n                        <div class=\"item-popular\"><\/div>\r\n                        <h3 class=\"ct-pricing-title\">Large Business<\/h3>\r\n                        <div class=\"ct-pricing-subtitle\">Unlimited Employees<\/div>\r\n                        <div class=\"ct-pricing-price1\">$699<\/div>\r\n                        \r\n                                                                            <div class=\"ct-pricing-icon\">\r\n                                                            <\/div>\r\n                        \r\n                        <div class=\"ct-pricing-desc\">Plus One-Time Bambee In-Depth HR Audit For:<\/div>\r\n                        <div class=\"ct-pricing-price2\">$3500<\/div>\r\n\r\n                                                    <div class=\"ct-pricing-button\">\r\n                                <a class=\"btn btn-default\" href=\"#buy-now #\">Try now<\/a>\r\n                            <\/div>\r\n                                            <\/div>\r\n                <\/div>\r\n                            <\/div>\r\n            <\/div>\r\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t            <\/div>\n        <\/div>\n                    <\/div>\n        <\/section>\n        <div class=\"elementor-element elementor-element-140ec90a e-con-full e-flex e-con e-parent\" data-id=\"140ec90a\" data-element_type=\"container\" id=\"buy-now\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-670739ce e-con-full e-flex e-con e-child\" data-id=\"670739ce\" data-element_type=\"container\">\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-535f0b03 e-con-full e-flex e-con e-child\" data-id=\"535f0b03\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4fd7d9a6 elementor-widget elementor-widget-heading\" data-id=\"4fd7d9a6\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Apply For Economy Package<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-58879646 elementor-widget elementor-widget-text-editor\" data-id=\"58879646\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p><style id=\"wpforms-css-vars-5390\">\n\t\t\t\t#wpforms-5390 {\n\t\t\t\t--wpforms-container-padding: 0px;\n--wpforms-container-border-width: 1px;\n--wpforms-container-border-radius: 3px;\n--wpforms-background-color: rgba(0, 0, 0, 0);\n--wpforms-field-size-input-height: 43px;\n--wpforms-field-size-input-spacing: 15px;\n--wpforms-field-size-font-size: 16px;\n--wpforms-field-size-line-height: 19px;\n--wpforms-field-size-padding-h: 14px;\n--wpforms-field-size-checkbox-size: 16px;\n--wpforms-field-size-sublabel-spacing: 5px;\n--wpforms-field-size-icon-size: 1;\n--wpforms-label-size-font-size: 16px;\n--wpforms-label-size-line-height: 19px;\n--wpforms-label-size-sublabel-font-size: 14px;\n--wpforms-label-size-sublabel-line-height: 17px;\n--wpforms-button-size-font-size: 17px;\n--wpforms-button-size-height: 41px;\n--wpforms-button-size-padding-h: 15px;\n--wpforms-button-size-margin-top: 10px;\n--wpforms-container-shadow-size-box-shadow: none;\n\t\t\t}\n\t\t\t<\/style><div class=\"wpforms-container wpforms-container-full wpforms-render-modern\" id=\"wpforms-5390\"><form id=\"wpforms-form-5390\" class=\"wpforms-validate wpforms-form wpforms-ajax-form\" data-formid=\"5390\" method=\"post\" enctype=\"multipart\/form-data\" action=\"\/iplastpackTanzania\/wp-json\/wp\/v2\/pages\/5360\" data-token=\"87493d2518eda42376bc4eb6119bccb7\" data-token-time=\"1784155065\"><noscript class=\"wpforms-error-noscript\">Please enable JavaScript in your browser to complete this form.<\/noscript><div id=\"wpforms-error-noscript\" style=\"display: none;\">Please enable JavaScript in your browser to complete this form.<\/div><div class=\"wpforms-field-container\"><div id=\"wpforms-5390-field_12-container\" class=\"wpforms-field wpforms-field-select wpforms-field-select-style-modern\" data-field-id=\"12\"><label class=\"wpforms-field-label wpforms-label-hide\" for=\"wpforms-5390-field_12\" aria-hidden=\"false\">Please select your desired option:<\/label><select id=\"wpforms-5390-field_12\" class=\"wpforms-field-large choicesjs-select\" data-size-class=\"wpforms-field-row wpforms-field-large\" data-search-enabled=\"\" name=\"wpforms[fields][12]\"><option value=\"\" class=\"placeholder\" disabled  selected='selected'>Please select your desired option:<\/option><option value=\"Option 1 : $3265\"  class=\"choice-27 depth-1\"  >Option 1 : $3265<\/option><option value=\"Option 2 : $3450\"  class=\"choice-30 depth-1\"  >Option 2 : $3450<\/option><option value=\"Option 3 : $4200\"  class=\"choice-31 depth-1\"  >Option 3 : $4200<\/option><\/select><\/div><div id=\"wpforms-5390-field_1-container\" class=\"wpforms-field wpforms-field-name\" data-field-id=\"1\"><fieldset><legend class=\"wpforms-field-label wpforms-label-hide\" aria-hidden=\"false\">Name <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/legend><div class=\"wpforms-field-row wpforms-field-large\"><div class=\"wpforms-field-row-block wpforms-first wpforms-one-half\"><input type=\"text\" id=\"wpforms-5390-field_1\" class=\"wpforms-field-name-first wpforms-field-required\" name=\"wpforms[fields][1][first]\" placeholder=\"First Name*\" aria-errormessage=\"wpforms-5390-field_1-error\" required><label for=\"wpforms-5390-field_1\" class=\"wpforms-field-sublabel after wpforms-sublabel-hide\">First<\/label><\/div><div class=\"wpforms-field-row-block wpforms-one-half\"><input type=\"text\" id=\"wpforms-5390-field_1-last\" class=\"wpforms-field-name-last wpforms-field-required\" name=\"wpforms[fields][1][last]\" placeholder=\"Last Name*\" aria-errormessage=\"wpforms-5390-field_1-last-error\" required><label for=\"wpforms-5390-field_1-last\" class=\"wpforms-field-sublabel after wpforms-sublabel-hide\">Last<\/label><\/div><\/div><\/fieldset><\/div><div id=\"wpforms-5390-field_2-container\" class=\"wpforms-field wpforms-field-email wpforms-one-half wpforms-first\" data-field-id=\"2\"><label class=\"wpforms-field-label wpforms-label-hide\" for=\"wpforms-5390-field_2\" aria-hidden=\"false\">Email <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><input type=\"email\" id=\"wpforms-5390-field_2\" class=\"wpforms-field-large wpforms-field-required\" name=\"wpforms[fields][2]\" placeholder=\"Your Email*\" spellcheck=\"false\" aria-errormessage=\"wpforms-5390-field_2-error\" required><\/div><div id=\"wpforms-5390-field_4-container\" class=\"wpforms-field wpforms-field-text wpforms-one-half\" data-field-id=\"4\"><label class=\"wpforms-field-label wpforms-label-hide\" for=\"wpforms-5390-field_4\" aria-hidden=\"false\">Company Name<\/label><input type=\"text\" id=\"wpforms-5390-field_4\" class=\"wpforms-field-large\" name=\"wpforms[fields][4]\" placeholder=\"Company Name\" aria-errormessage=\"wpforms-5390-field_4-error\" ><\/div><div id=\"wpforms-5390-field_5-container\" class=\"wpforms-field wpforms-field-text wpforms-one-half wpforms-first\" data-field-id=\"5\"><label class=\"wpforms-field-label wpforms-label-hide\" for=\"wpforms-5390-field_5\" aria-hidden=\"false\">Address<\/label><input type=\"text\" id=\"wpforms-5390-field_5\" class=\"wpforms-field-large\" name=\"wpforms[fields][5]\" placeholder=\"Address\" aria-errormessage=\"wpforms-5390-field_5-error\" ><\/div><div id=\"wpforms-5390-field_6-container\" class=\"wpforms-field wpforms-field-text wpforms-one-half\" data-field-id=\"6\"><label class=\"wpforms-field-label wpforms-label-hide\" for=\"wpforms-5390-field_6\" aria-hidden=\"false\">Phone Number<\/label><input type=\"text\" id=\"wpforms-5390-field_6\" class=\"wpforms-field-large\" name=\"wpforms[fields][6]\" placeholder=\"Phone Number\" aria-errormessage=\"wpforms-5390-field_6-error\" ><\/div><div id=\"wpforms-5390-field_10-container\" class=\"wpforms-field wpforms-field-text wpforms-one-half wpforms-first\" data-field-id=\"10\"><label class=\"wpforms-field-label wpforms-label-hide\" for=\"wpforms-5390-field_10\" aria-hidden=\"false\">Fax<\/label><input type=\"text\" id=\"wpforms-5390-field_10\" class=\"wpforms-field-large\" name=\"wpforms[fields][10]\" placeholder=\"Fax\" aria-errormessage=\"wpforms-5390-field_10-error\" ><\/div><div id=\"wpforms-5390-field_7-container\" class=\"wpforms-field wpforms-field-text wpforms-one-half\" data-field-id=\"7\"><label class=\"wpforms-field-label wpforms-label-hide\" for=\"wpforms-5390-field_7\" aria-hidden=\"false\">City<\/label><input type=\"text\" id=\"wpforms-5390-field_7\" class=\"wpforms-field-large\" name=\"wpforms[fields][7]\" placeholder=\"City\" aria-errormessage=\"wpforms-5390-field_7-error\" ><\/div><div id=\"wpforms-5390-field_8-container\" class=\"wpforms-field wpforms-field-text wpforms-one-half wpforms-first\" data-field-id=\"8\"><label class=\"wpforms-field-label wpforms-label-hide\" for=\"wpforms-5390-field_8\" aria-hidden=\"false\">Country<\/label><input type=\"text\" id=\"wpforms-5390-field_8\" class=\"wpforms-field-large\" name=\"wpforms[fields][8]\" placeholder=\"Country\" aria-errormessage=\"wpforms-5390-field_8-error\" ><\/div>\t\t<div id=\"wpforms-5390-field_3-container\"\n\t\t\tclass=\"wpforms-field wpforms-field-text\"\n\t\t\tdata-field-type=\"text\"\n\t\t\tdata-field-id=\"3\"\n\t\t\t>\n\t\t\t<label class=\"wpforms-field-label\" for=\"wpforms-5390-field_3\" >Phone Email option:<\/label>\n\t\t\t<input type=\"text\" id=\"wpforms-5390-field_3\" class=\"wpforms-field-medium\" name=\"wpforms[fields][3]\" >\n\t\t<\/div>\n\t\t<div id=\"wpforms-5390-field_9-container\" class=\"wpforms-field wpforms-field-text wpforms-one-half\" data-field-id=\"9\"><label class=\"wpforms-field-label wpforms-label-hide\" for=\"wpforms-5390-field_9\" aria-hidden=\"false\">Designation<\/label><input type=\"text\" id=\"wpforms-5390-field_9\" class=\"wpforms-field-large\" name=\"wpforms[fields][9]\" placeholder=\"Designation\" aria-errormessage=\"wpforms-5390-field_9-error\" ><\/div><div id=\"wpforms-5390-field_11-container\" class=\"wpforms-field wpforms-field-text wpforms-one-half wpforms-first\" data-field-id=\"11\"><label class=\"wpforms-field-label wpforms-label-hide\" for=\"wpforms-5390-field_11\" aria-hidden=\"false\">Product<\/label><input type=\"text\" id=\"wpforms-5390-field_11\" class=\"wpforms-field-large\" name=\"wpforms[fields][11]\" placeholder=\"Product\" aria-errormessage=\"wpforms-5390-field_11-error\" ><\/div><div id=\"wpforms-5390-field_13-container\" class=\"wpforms-field wpforms-field-text wpforms-one-half\" data-field-id=\"13\"><label class=\"wpforms-field-label wpforms-label-hide\" for=\"wpforms-5390-field_13\" aria-hidden=\"false\">Website<\/label><input type=\"text\" id=\"wpforms-5390-field_13\" class=\"wpforms-field-large\" name=\"wpforms[fields][13]\" placeholder=\"Website\" aria-errormessage=\"wpforms-5390-field_13-error\" ><\/div><script>\n\t\t\t\t( function() {\n\t\t\t\t\tconst style = document.createElement( 'style' );\n\t\t\t\t\tstyle.appendChild( document.createTextNode( '#wpforms-5390-field_3-container { position: absolute !important; overflow: hidden !important; display: inline !important; height: 1px !important; width: 1px !important; z-index: -1000 !important; padding: 0 !important; } #wpforms-5390-field_3-container input { visibility: hidden; } #wpforms-conversational-form-page #wpforms-5390-field_3-container label { counter-increment: none; }' ) );\n\t\t\t\t\tdocument.head.appendChild( style );\n\t\t\t\t\tdocument.currentScript?.remove();\n\t\t\t\t} )();\n\t\t\t<\/script><\/div><!-- .wpforms-field-container --><div class=\"wpforms-submit-container\" ><input type=\"hidden\" name=\"wpforms[id]\" value=\"5390\"><input type=\"hidden\" name=\"page_title\" value=\"\"><input type=\"hidden\" name=\"page_url\" value=\"https:\/\/mxmexhibitions.com\/iplastpackTanzania\/wp-json\/wp\/v2\/pages\/5360\"><input type=\"hidden\" name=\"url_referer\" value=\"\"><button type=\"submit\" name=\"wpforms[submit]\" id=\"wpforms-submit-5390\" class=\"wpforms-submit\" data-alt-text=\"Sending...\" data-submit-text=\"Submit Application\" aria-live=\"assertive\" value=\"wpforms-submit\">Submit Application<\/button><img decoding=\"async\" src=\"https:\/\/mxmexhibitions.com\/iplastpackTanzania\/wp-content\/plugins\/wpforms-lite\/assets\/images\/submit-spin.svg\" class=\"wpforms-submit-spinner\" style=\"display: none;\" width=\"26\" height=\"26\" alt=\"Loading\"><\/div><\/form><\/div>  <!-- .wpforms-container --><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-76022466 e-con-full e-flex e-con e-child\" data-id=\"76022466\" data-element_type=\"container\">\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Economy Package Basic Provisions 9 Sqm Octanorm Stand 1 Table &#8211; 2 Chairs &#8211; Electrical Socket 220 Volts &#8211; 2 Spot Lights. Company Name Fascia &amp; Carpet. Listing in Exhibition Catalog. 4 nights \/ 5 days 4 **** Hotel Accommodation. Airport to Hotel &amp; Back to Airport. Hotel to Exhibition Centre &amp; Back to Hotel [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-5360","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/mxmexhibitions.com\/iplastpackTanzania\/wp-json\/wp\/v2\/pages\/5360","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mxmexhibitions.com\/iplastpackTanzania\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/mxmexhibitions.com\/iplastpackTanzania\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/mxmexhibitions.com\/iplastpackTanzania\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/mxmexhibitions.com\/iplastpackTanzania\/wp-json\/wp\/v2\/comments?post=5360"}],"version-history":[{"count":31,"href":"https:\/\/mxmexhibitions.com\/iplastpackTanzania\/wp-json\/wp\/v2\/pages\/5360\/revisions"}],"predecessor-version":[{"id":5398,"href":"https:\/\/mxmexhibitions.com\/iplastpackTanzania\/wp-json\/wp\/v2\/pages\/5360\/revisions\/5398"}],"wp:attachment":[{"href":"https:\/\/mxmexhibitions.com\/iplastpackTanzania\/wp-json\/wp\/v2\/media?parent=5360"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}